{"id":25875,"date":"2023-01-11T20:33:33","date_gmt":"2023-01-11T20:33:33","guid":{"rendered":"https:\/\/thinkdifferently-actdifferently.eu\/?page_id=25875"},"modified":"2023-11-03T20:44:08","modified_gmt":"2023-11-03T18:44:08","slug":"second-quiz-children","status":"publish","type":"page","link":"https:\/\/thinkdifferently-actdifferently.eu\/pt\/second-quiz-children\/","title":{"rendered":"Second Quiz Children"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"25875\" class=\"elementor elementor-25875\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c2d1cad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c2d1cad\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2ec9107\" data-id=\"2ec9107\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d34ef6 elementor-widget elementor-widget-heading\" data-id=\"5d34ef6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vamos testar o teu conhecimento!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b3ece5 croatianprint ekit_wpForms_container-form-button-custom elementor-widget elementor-widget-elementskit-wp-forms\" data-id=\"9b3ece5\" data-element_type=\"widget\" data-widget_type=\"elementskit-wp-forms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con ekit_wpForms_container\"><div class=\"wpforms-container\" id=\"wpforms-27171\"><form id=\"wpforms-form-27171\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"27171\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/pt\/wp-json\/wp\/v2\/pages\/25875\" data-token=\"059b7bf2e211dcd74d45608135011068\" data-token-time=\"1778697612\" data-trp-original-action=\"\/pt\/wp-json\/wp\/v2\/pages\/25875\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-27171-field_5-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-27171-field_5\">Predmeti koji su napravljeni i\/ili kori\u0161teni od biljaka: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27171-field_5\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][5]\" required><\/div><div id=\"wpforms-27171-field_4-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-27171-field_4\">Predmeti koji su napravljeni i\/ili kori\u0161teni od \u017eivotinja: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27171-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" required><\/div><div id=\"wpforms-27171-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-27171-field_3\">Predmeti koji su napravljeni i\/ili kori\u0161teni od fosilnih goriva: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27171-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" required><\/div><div id=\"wpforms-27171-field_1-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-27171-field_1\">Predmeti koji su napravljeni i\/ili kori\u0161teni od minerala: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27171-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" required><\/div><div id=\"wpforms-27171-field_2-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-27171-field_2\">Predmeti koji su napravljeni i\/ili kori\u0161teni od vode, zraka, Sunca: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27171-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/div><div id=\"wpforms-27171-field_6-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-27171-field_6\">Email<\/label><input type=\"email\" id=\"wpforms-27171-field_6\" class=\"wpforms-field-medium\" name=\"wpforms[fields][6]\" spellcheck=\"false\" ><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"27171\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/thinkdifferently-actdifferently.eu\/pt\/wp-json\/wp\/v2\/pages\/25875\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-27171\" class=\"wpforms-submit\" data-alt-text=\"Slanje...\" data-submit-text=\"Potvrdi\" aria-live=\"assertive\" value=\"wpforms-submit\">Potvrdi<\/button><img decoding=\"async\" src=\"https:\/\/thinkdifferently-actdifferently.eu\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"pt\"\/><\/form><\/div>  <!-- .wpforms-container --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77b04a8 englishprint ekit_wpForms_container-form-button-custom elementor-widget elementor-widget-elementskit-wp-forms\" data-id=\"77b04a8\" data-element_type=\"widget\" data-widget_type=\"elementskit-wp-forms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con ekit_wpForms_container\"><div class=\"wpforms-container\" id=\"wpforms-27127\"><form id=\"wpforms-form-27127\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"27127\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/pt\/wp-json\/wp\/v2\/pages\/25875\" data-token=\"efd33486db9b52b349735f06dbfd9f04\" data-token-time=\"1778697612\" data-trp-original-action=\"\/pt\/wp-json\/wp\/v2\/pages\/25875\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-27127-field_5-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-27127-field_5\">Coisas que s\u00e3o feitas e\/ou utilizadas a partir de plantas: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27127-field_5\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][5]\" required><\/div><div id=\"wpforms-27127-field_4-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-27127-field_4\">Coisas que s\u00e3o feitas e\/ou utilizadas a partir de animais: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27127-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" required><\/div><div id=\"wpforms-27127-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-27127-field_3\">Coisas que s\u00e3o feitas e\/ou utilizadas a partir de combust\u00edveis f\u00f3sseis: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27127-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" required><\/div><div id=\"wpforms-27127-field_1-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-27127-field_1\">Coisas que s\u00e3o feitas e\/ou utilizadas a partir de minerais: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27127-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" required><\/div><div id=\"wpforms-27127-field_2-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-27127-field_2\">Coisas que s\u00e3o feitas e\/ou utilizadas a partir da \u00e1gua, do ar ou do sol: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27127-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/div><div id=\"wpforms-27127-field_6-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-27127-field_6\">Email<\/label><input type=\"email\" id=\"wpforms-27127-field_6\" class=\"wpforms-field-medium\" name=\"wpforms[fields][6]\" spellcheck=\"false\" ><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"27127\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/thinkdifferently-actdifferently.eu\/pt\/wp-json\/wp\/v2\/pages\/25875\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-27127\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img decoding=\"async\" src=\"https:\/\/thinkdifferently-actdifferently.eu\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"pt\"\/><\/form><\/div>  <!-- .wpforms-container --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df596aa pttest ekit_wpForms_container-form-button-custom elementor-widget elementor-widget-elementskit-wp-forms\" data-id=\"df596aa\" data-element_type=\"widget\" data-widget_type=\"elementskit-wp-forms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con ekit_wpForms_container\"><div class=\"wpforms-container\" id=\"wpforms-27455\"><form id=\"wpforms-form-27455\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"27455\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/pt\/wp-json\/wp\/v2\/pages\/25875\" data-token=\"3de3375497e3f030f1f418b8c2f3ec74\" data-token-time=\"1778697612\" data-trp-original-action=\"\/pt\/wp-json\/wp\/v2\/pages\/25875\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-27455-field_5-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-27455-field_5\">Coisas que s\u00e3o feitas e\/ou usadas de plantas: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27455-field_5\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][5]\" required><\/div><div id=\"wpforms-27455-field_4-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-27455-field_4\">Coisas que s\u00e3o feitas e\/ou usadas de animais: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27455-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" required><\/div><div id=\"wpforms-27455-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-27455-field_3\">Coisas que s\u00e3o feitas e\/ou usadas a partir de combust\u00edveis f\u00f3sseis: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27455-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" required><\/div><div id=\"wpforms-27455-field_1-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-27455-field_1\">Coisas que s\u00e3o feitas e\/ou usadas a partir de minerais: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27455-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" required><\/div><div id=\"wpforms-27455-field_2-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-27455-field_2\">Coisas que s\u00e3o feitas e\/ou usadas de \u00e1gua, ar ou sol: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27455-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/div><div id=\"wpforms-27455-field_6-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-27455-field_6\">Email<\/label><input type=\"email\" id=\"wpforms-27455-field_6\" class=\"wpforms-field-medium\" name=\"wpforms[fields][6]\" spellcheck=\"false\" ><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"27455\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/thinkdifferently-actdifferently.eu\/pt\/wp-json\/wp\/v2\/pages\/25875\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-27455\" class=\"wpforms-submit\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><img decoding=\"async\" src=\"https:\/\/thinkdifferently-actdifferently.eu\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"pt\"\/><\/form><\/div>  <!-- .wpforms-container --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b94cb8 rotest ekit_wpForms_container-form-button-custom elementor-widget elementor-widget-elementskit-wp-forms\" data-id=\"1b94cb8\" data-element_type=\"widget\" data-widget_type=\"elementskit-wp-forms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con ekit_wpForms_container\"><div class=\"wpforms-container\" id=\"wpforms-27471\"><form id=\"wpforms-form-27471\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"27471\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/pt\/wp-json\/wp\/v2\/pages\/25875\" data-token=\"345d7181d092ed85823d39d45bc48472\" data-token-time=\"1778697612\" data-trp-original-action=\"\/pt\/wp-json\/wp\/v2\/pages\/25875\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-27471-field_5-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-27471-field_5\">Lucruri care sunt f\u0103cute \u0219i \/ sau folosite din plante: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27471-field_5\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][5]\" required><\/div><div id=\"wpforms-27471-field_4-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-27471-field_4\">Lucruri care sunt f\u0103cute \u0219i\/sau folosite din animale: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27471-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" required><\/div><div id=\"wpforms-27471-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-27471-field_3\">Lucruri care sunt fabricate \u0219i \/ sau utilizate din combustibili fosili: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27471-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" required><\/div><div id=\"wpforms-27471-field_1-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-27471-field_1\">Lucruri care sunt fabricate \u0219i \/ sau utilizate din minerale: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27471-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" required><\/div><div id=\"wpforms-27471-field_2-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-27471-field_2\">Lucruri care sunt f\u0103cute \u0219i\/sau folosite din ap\u0103, aer sau soare: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27471-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/div><div id=\"wpforms-27471-field_6-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-27471-field_6\">Email<\/label><input type=\"email\" id=\"wpforms-27471-field_6\" class=\"wpforms-field-medium\" name=\"wpforms[fields][6]\" spellcheck=\"false\" ><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"27471\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/thinkdifferently-actdifferently.eu\/pt\/wp-json\/wp\/v2\/pages\/25875\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-27471\" class=\"wpforms-submit\" data-alt-text=\"Trimiterea...\" data-submit-text=\"Trimite\u021bi\" aria-live=\"assertive\" value=\"wpforms-submit\">Trimite\u021bi<\/button><img decoding=\"async\" src=\"https:\/\/thinkdifferently-actdifferently.eu\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"pt\"\/><\/form><\/div>  <!-- .wpforms-container --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33c1228 greektest ekit_wpForms_container-form-button-custom elementor-widget elementor-widget-elementskit-wp-forms\" data-id=\"33c1228\" data-element_type=\"widget\" data-widget_type=\"elementskit-wp-forms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con ekit_wpForms_container\"><div class=\"wpforms-container\" id=\"wpforms-27240\"><form id=\"wpforms-form-27240\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"27240\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/pt\/wp-json\/wp\/v2\/pages\/25875\" data-token=\"9e5f56a06266d56c2747b87f8c87f485\" data-token-time=\"1778697612\" data-trp-original-action=\"\/pt\/wp-json\/wp\/v2\/pages\/25875\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-27240-field_5-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-27240-field_5\">\u03a0\u03c1\u03ac\u03b3\u03bc\u03b1\u03c4\u03b1 \u03c0\u03bf\u03c5 \u03ba\u03b1\u03c4\u03b1\u03c3\u03ba\u03b5\u03c5\u03ac\u03b6\u03bf\u03bd\u03c4\u03b1\u03b9 \u03ae\/\u03ba\u03b1\u03b9 \u03c7\u03c1\u03b7\u03c3\u03b9\u03bc\u03bf\u03c0\u03bf\u03b9\u03bf\u03cd\u03bd\u03c4\u03b1\u03b9 \u03b1\u03c0\u03cc \u03c6\u03c5\u03c4\u03ac: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27240-field_5\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][5]\" required><\/div><div id=\"wpforms-27240-field_4-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-27240-field_4\">\u03a0\u03c1\u03ac\u03b3\u03bc\u03b1\u03c4\u03b1 \u03c0\u03bf\u03c5 \u03ba\u03b1\u03c4\u03b1\u03c3\u03ba\u03b5\u03c5\u03ac\u03b6\u03bf\u03bd\u03c4\u03b1\u03b9 \u03ae\/\u03ba\u03b1\u03b9 \u03c7\u03c1\u03b7\u03c3\u03b9\u03bc\u03bf\u03c0\u03bf\u03b9\u03bf\u03cd\u03bd\u03c4\u03b1\u03b9 \u03b1\u03c0\u03cc \u03b6\u03ce\u03b1: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27240-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" required><\/div><div id=\"wpforms-27240-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-27240-field_3\">\u03a0\u03c1\u03ac\u03b3\u03bc\u03b1\u03c4\u03b1 \u03c0\u03bf\u03c5 \u03ba\u03b1\u03c4\u03b1\u03c3\u03ba\u03b5\u03c5\u03ac\u03b6\u03bf\u03bd\u03c4\u03b1\u03b9 \u03ae\/\u03ba\u03b1\u03b9 \u03c7\u03c1\u03b7\u03c3\u03b9\u03bc\u03bf\u03c0\u03bf\u03b9\u03bf\u03cd\u03bd\u03c4\u03b1\u03b9 \u03b1\u03c0\u03cc \u03bf\u03c1\u03c5\u03ba\u03c4\u03ac \u03ba\u03b1\u03c5\u03c3\u03af\u03bc\u03c9\u03bd: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27240-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" required><\/div><div id=\"wpforms-27240-field_1-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-27240-field_1\">\u03a0\u03c1\u03ac\u03b3\u03bc\u03b1\u03c4\u03b1 \u03c0\u03bf\u03c5 \u03ba\u03b1\u03c4\u03b1\u03c3\u03ba\u03b5\u03c5\u03ac\u03b6\u03bf\u03bd\u03c4\u03b1\u03b9 \u03ae\/\u03ba\u03b1\u03b9 \u03c7\u03c1\u03b7\u03c3\u03b9\u03bc\u03bf\u03c0\u03bf\u03b9\u03bf\u03cd\u03bd\u03c4\u03b1\u03b9 \u03b1\u03c0\u03cc \u03bc\u03b5\u03c4\u03b1\u03bb\u03bb\u03b5\u03cd\u03bc\u03b1\u03c4\u03b1: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27240-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" required><\/div><div id=\"wpforms-27240-field_2-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-27240-field_2\">\u03a0\u03c1\u03ac\u03b3\u03bc\u03b1\u03c4\u03b1 \u03c0\u03bf\u03c5 \u03ba\u03b1\u03c4\u03b1\u03c3\u03ba\u03b5\u03c5\u03ac\u03b6\u03bf\u03bd\u03c4\u03b1\u03b9 \u03ae\/\u03ba\u03b1\u03b9 \u03c7\u03c1\u03b7\u03c3\u03b9\u03bc\u03bf\u03c0\u03bf\u03b9\u03bf\u03cd\u03bd\u03c4\u03b1\u03b9 \u03b1\u03c0\u03cc \u03c4\u03bf \u03bd\u03b5\u03c1\u03cc, \u03c4\u03bf\u03bd \u03b1\u03ad\u03c1\u03b1 \u03ae \u03c4\u03bf\u03bd \u03ae\u03bb\u03b9\u03bf: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27240-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/div><div id=\"wpforms-27240-field_6-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-27240-field_6\">Email<\/label><input type=\"email\" id=\"wpforms-27240-field_6\" class=\"wpforms-field-medium\" name=\"wpforms[fields][6]\" spellcheck=\"false\" ><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"27240\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/thinkdifferently-actdifferently.eu\/pt\/wp-json\/wp\/v2\/pages\/25875\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-27240\" class=\"wpforms-submit\" data-alt-text=\"\u0391\u03c0\u03bf\u03c3\u03c4\u03bf\u03bb\u03ae...\" data-submit-text=\"\u03a5\u03c0\u03bf\u03b2\u03bf\u03bb\u03ae\" aria-live=\"assertive\" value=\"wpforms-submit\">\u03a5\u03c0\u03bf\u03b2\u03bf\u03bb\u03ae<\/button><img decoding=\"async\" src=\"https:\/\/thinkdifferently-actdifferently.eu\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"pt\"\/><\/form><\/div>  <!-- .wpforms-container --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc9e72c spanishtest ekit_wpForms_container-form-button-custom elementor-widget elementor-widget-elementskit-wp-forms\" data-id=\"bc9e72c\" data-element_type=\"widget\" data-widget_type=\"elementskit-wp-forms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con ekit_wpForms_container\"><div class=\"wpforms-container\" id=\"wpforms-27243\"><form id=\"wpforms-form-27243\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"27243\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/pt\/wp-json\/wp\/v2\/pages\/25875\" data-token=\"7918bace911ba36bc6ff3a7d0896519c\" data-token-time=\"1778697612\" data-trp-original-action=\"\/pt\/wp-json\/wp\/v2\/pages\/25875\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-27243-field_5-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-27243-field_5\">Cosas que se elaboran y\/o utilizan a partir de plantas: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27243-field_5\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][5]\" required><\/div><div id=\"wpforms-27243-field_4-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-27243-field_4\">Cosas que se elaboran y\/o utilizan a partir de animales: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27243-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" required><\/div><div id=\"wpforms-27243-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-27243-field_3\">Cosas que se elaboran y\/o utilizan a partir de combustibles f\u00f3siles: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27243-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" required><\/div><div id=\"wpforms-27243-field_1-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-27243-field_1\">Cosas que se elaboran y\/o utilizan a partir de minerales: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27243-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" required><\/div><div id=\"wpforms-27243-field_2-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-27243-field_2\">Cosas que se elaboran y\/o utilizan a partir del agua, el aire o el sol: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27243-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/div><div id=\"wpforms-27243-field_6-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-27243-field_6\">Email<\/label><input type=\"email\" id=\"wpforms-27243-field_6\" class=\"wpforms-field-medium\" name=\"wpforms[fields][6]\" spellcheck=\"false\" ><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"27243\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/thinkdifferently-actdifferently.eu\/pt\/wp-json\/wp\/v2\/pages\/25875\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-27243\" class=\"wpforms-submit\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><img decoding=\"async\" src=\"https:\/\/thinkdifferently-actdifferently.eu\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"pt\"\/><\/form><\/div>  <!-- .wpforms-container --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0c32a9 elementor-widget elementor-widget-html\" data-id=\"a0c32a9\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n    .translatepress-en_US .croatianprint {\ndisplay: none !important;\n}\n.translatepress-hr .englishprint {\ndisplay: none !important;\n}\n.translatepress-hr #englishprint {\ndisplay: none !important;\n}\n<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c8ddfc elementor-widget elementor-widget-html\" data-id=\"3c8ddfc\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n    .translatepress-en_US .croatiantest  {\ndisplay: none !important;\n}\n.translatepress-en_US .greektest  {\ndisplay: none !important;\n}\n.translatepress-en_US .spanishtest  {\ndisplay: none !important;\n}\n.translatepress-en_US .pttest  {\ndisplay: none !important;\n}\n.translatepress-en_US .rotest  {\ndisplay: none !important;\n}\n.translatepress-hr .englishtest {\ndisplay: none !important;\n}\n.translatepress-hr .greektest {\ndisplay: none !important;\n}\n.translatepress-hr .spanishtest {\ndisplay: none !important;\n}\n.translatepress-hr .rotest {\ndisplay: none !important;\n}\n.translatepress-hr .pttest {\ndisplay: none !important;\n}\n.translatepress-el .englishtest {\ndisplay: none !important;\n}\n.translatepress-el .croatiantest {\ndisplay: none !important;\n}\n.translatepress-el .spanishtest {\ndisplay: none !important;\n}\n.translatepress-el .rotest {\ndisplay: none !important;\n}\n.translatepress-el .pttest {\ndisplay: none !important;\n}\n.translatepress-es_ES .croatiantest {\ndisplay: none !important;\n}\n.translatepress-es_ES .englishtest {\ndisplay: none !important;\n}\n.translatepress-es_ES .greektest {\ndisplay: none !important;\n}\n.translatepress-es_ES .rotest {\ndisplay: none !important;\n}\n.translatepress-es_ES .pttest {\ndisplay: none !important;\n}\n\n\n.translatepress-pt_PT .croatianprint {\ndisplay: none !important;\n}\n.translatepress-pt_PT .englishprint {\ndisplay: none !important;\n}\n.translatepress-pt_PT .greektest {\ndisplay: none !important;\n}\n.translatepress-pt_PT .rotest {\ndisplay: none !important;\n}\n.translatepress-pt_PT .spanishtest {\ndisplay: none !important;\n}\n\n\n.translatepress-ro_RO .croatianprint {\ndisplay: none !important;\n}\n.translatepress-ro_RO .englishprint {\ndisplay: none !important;\n}\n.translatepress-ro_RO .greektest {\ndisplay: none !important;\n}\n.translatepress-ro_RO .pttest {\ndisplay: none !important;\n}\n.translatepress-ro_RO .spanishtest {\ndisplay: none !important;\n}\n<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Let&#8217;s test your knowledge! Please enable JavaScript in your browser to complete this form.Predmeti koji su napravljeni i\/ili kori\u0161teni od biljaka: *Predmeti koji su napravljeni i\/ili kori\u0161teni od \u017eivotinja: *Predmeti koji su napravljeni i\/ili kori\u0161teni od fosilnih goriva: *Predmeti koji su napravljeni i\/ili kori\u0161teni od minerala: *Predmeti koji su napravljeni i\/ili kori\u0161teni od vode, zraka, [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/thinkdifferently-actdifferently.eu\/pt\/wp-json\/wp\/v2\/pages\/25875"}],"collection":[{"href":"https:\/\/thinkdifferently-actdifferently.eu\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/thinkdifferently-actdifferently.eu\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/thinkdifferently-actdifferently.eu\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thinkdifferently-actdifferently.eu\/pt\/wp-json\/wp\/v2\/comments?post=25875"}],"version-history":[{"count":22,"href":"https:\/\/thinkdifferently-actdifferently.eu\/pt\/wp-json\/wp\/v2\/pages\/25875\/revisions"}],"predecessor-version":[{"id":27485,"href":"https:\/\/thinkdifferently-actdifferently.eu\/pt\/wp-json\/wp\/v2\/pages\/25875\/revisions\/27485"}],"wp:attachment":[{"href":"https:\/\/thinkdifferently-actdifferently.eu\/pt\/wp-json\/wp\/v2\/media?parent=25875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}